{"id":11318,"date":"2014-11-27T09:12:31","date_gmt":"2014-11-27T08:12:31","guid":{"rendered":"http:\/\/blog.vendiauto.com\/?p=11318"},"modified":"2016-09-14T14:46:18","modified_gmt":"2016-09-14T13:46:18","slug":"in-arrivo-la-nuova-ford-mondeo-ibrida","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/in-arrivo-la-nuova-ford-mondeo-ibrida-2014","title":{"rendered":"In arrivo la nuova Ford Mondeo ibrida!"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-11321\" src=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/11\/cq5dam.web_.960.8003.jpeg\" alt=\"cq5dam.web.960.800\" width=\"540\" height=\"362\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/11\/cq5dam.web_.960.8003.jpeg 830w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/11\/cq5dam.web_.960.8003-300x200.jpeg 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/p>\n<p>Presentata durante lo scorso Salone di Parigi, la nuova Ford Mondeo, di cui avevamo gi\u00e0 parlato in <a href=\"https:\/\/vendiauto.com\/blog\/la-nuova-ford-mondeo-sbarca-in-europa-2014\" target=\"_blank\">questo post<\/a> qualche settimana fa, \u00a0si appresta ad essere commercializzata in tutta Europa all&#8217;inizio del 2015. Se dal punto di vista delle linee e delle dotazioni di accessori non \u00e8 cambiato nulla dallo scorso ottobre, non si pu\u00f2 dire lo stesso per quanto concerne la tecnica.<\/p>\n<p><!--more--><\/p>\n<p>Difatti il debutto della nuova generazione della grande berlina Ford sar\u00e0 caratterizzato anche dalla presenza della variante ibrida, novit\u00e0 assoluta per la berlina americana. La nuova Mondeo, oltre alle classiche motorizzazioni benzina e diesel, sar\u00e0 disponibile anche nella variante ibrida: in questa versione che di base sar\u00e0 equipaggiata con il motore benzina 2.000 di cilindrata, sar\u00e0 abbinato un motore elettrico alimentato con batterie al litio da 1,4 kwh. I due motori consentiranno alla berlina dell&#8217;ovale blu di poter contare su una potenza di ben 187 cv a fronte di emissioni contenute in soli 99 g\/km di co2. La Mondeo Hybrid potr\u00e0 raggiungere i 135 km\/h nella sola modalit\u00e0 elettrica e sfruttare i 187 cv dei due motori, elettrico e termico, solo quando servir\u00e0 molta potenza. La nuova ibrida di Ford sar\u00e0 disponibile in Italia ad un prezzo unico di 32.500 euro basato sulla versione pi\u00f9 ricca di accessori denominata Titanium.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/auto-elettriche-dal-2013-arrivano-gli-incentivi-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/05\/auto-elettrica-incentivi-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Auto elettriche: dal 2013 arrivano gli incentivi<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/fiat-professional-al-salone-internazionale-di-hannover-2012-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/09\/Fiat-Professional-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Fiat Professional al Salone Internazionale di Hann...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/a-presto-la-nuova-honda-nsx-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/02\/Honda-NSX-0-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">A presto la nuova Honda NSX?<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ecall-il-nuovo-sistema-di-chiamata-demergenza-mercedes-benz-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/03\/mercedes-benz-e-call-il-nuovo-sistema-di-chiamata-d-emergenza-ecall2-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">eCall: il nuovo sistema di chiamata d\u2019emerge...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Presentata durante lo scorso Salone di Parigi, la nuova Ford Mondeo, di cui avevamo gi\u00e0 parlato in questo post qualche settimana fa, \u00a0si appresta ad essere commercializzata in tutta Europa all&#8217;inizio del 2015. Se dal punto di vista delle linee e delle dotazioni di accessori non \u00e8 cambiato nulla dallo scorso ottobre, non si pu\u00f2 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[24,1974,1917],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/11318"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=11318"}],"version-history":[{"count":3,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/11318\/revisions"}],"predecessor-version":[{"id":11323,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/11318\/revisions\/11323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media\/11321"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=11318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=11318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=11318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}