{"id":12097,"date":"2016-09-08T11:41:04","date_gmt":"2016-09-08T10:41:04","guid":{"rendered":"http:\/\/blog.vendiauto.com\/?p=12097"},"modified":"2016-09-14T14:45:31","modified_gmt":"2016-09-14T13:45:31","slug":"audi-q2-vivace-e-silenziosa","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/audi-q2-vivace-e-silenziosa-2016","title":{"rendered":"Audi Q2: vivace e silenziosa"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-12098\" src=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/Audi-Q2.jpg\" alt=\"audi-q2\" width=\"530\" height=\"350\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/Audi-Q2.jpg 530w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/Audi-Q2-300x198.jpg 300w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\">Dimensioni contenute, rifinita nei dettagli, vivace nei motori e linee robuste: \u00e8 la nuova Audi Q2 che arriver\u00e0 in Italia in autunno.<span style=\"line-height: 1.5;\">E\u2019 la pi\u00f9 piccola tra le Suv della casa tedesca : lunga 419 cm, larga 179 cm e alta 151 cm compatta ma dalla linea robusta \u00a0per conservare il\u00a0carattere possente tipico dei Suv Audi.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-12100\" src=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-interni.jpg\" alt=\"audi-q2-2016-interni\" width=\"530\" height=\"350\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-interni.jpg 530w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-interni-300x198.jpg 300w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"line-height: 1.5;\">Ben fatta sia esteticamente, con angoli e spigoli e un frontale che colpisce grazie a un&#8217;ampia mascherina che contiene, che negli interni con l\u2019abitacolo \u00a0spazioso e \u00a0ben rifinito. Il bagagliaio ha una buona capacit\u00e0: 405 litri. Tuttavia, la capienza a divano abbassato (1050 litri) \u00e8 inferiore a quella della maggior parte delle suv e crossover di dimensioni simili. L&#8217;Audi Q2 seppur contenuta nelle dimensioni ha tutte le caratteristiche di un grande Suv con il vantaggio di adattarsi bene anche al traffico cittadino.<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-12099\" src=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016.jpg\" alt=\"audi-q2-2016\" width=\"530\" height=\"350\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016.jpg 530w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-300x198.jpg 300w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\">Un&#8217;auto\u00a0realizzata con pregevole cura nelle finiture, il motore \u00e8 poco rumoroso e la tenuta di strada \u00e8 degna di un vero suv.<\/p>\n<p style=\"text-align: justify;\">La gamma di motori annuncia il 1.0, 1.4 e 2.0 TFSI a benzina (con 116, 150 e 190 cavalli rispettivamente) e, a gasolio, il 1.6 TDI da 116 e il 2.0 con 150 o 190 cavalli; trazione anteriore o integrale quattro, cambi manuali o a doppia frizione S tronic.<\/p>\n<p style=\"text-align: justify;\">\n<img loading=\"lazy\" class=\"aligncenter size-full wp-image-12101\" src=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/Audi-Q2-comandi.jpg\" alt=\"audi-q2-comandi\" width=\"530\" height=\"350\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/Audi-Q2-comandi.jpg 530w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/Audi-Q2-comandi-300x198.jpg 300w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\">Tra la dotazione di serie sono tanti \u00a0sistemi elettronici di assistenza per il guidatore uno tra tutti l\u2019Audi pre sense front che riconosce le situazioni critiche causate da altri veicoli o pedoni che si incrociano attiva se serve \u00a0una frenata d\u2019emergenza alle basse velocit\u00e0, anche fino all&#8217;arresto del veicolo.<\/p>\n<p style=\"text-align: justify;\">Alcuni comandi come ad esempio le frecce d\u2019emergenza sono forse poco visibili e volendo evidenziare dei piccoli difetti le sospensioni sono leggermente rigide e il comfort in caso di buche non \u00e8 dei migliori.<\/p>\n<p style=\"text-align: justify;\">L\u2019Audi Q2 arriver\u00e0 nelle concessionarie a novembre ma da luglio \u00e8 comunque possibile effettuare un pre-ordine per \u00a0\u201cbloccare\u201d gli esemplari che verranno consegnati per primi.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-12102\" src=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-posteriore.jpg\" alt=\"audi-q2-2016-posteriore\" width=\"530\" height=\"350\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-posteriore.jpg 530w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/09\/audi-q2-2016-posteriore-300x198.jpg 300w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/p>\n<p style=\"text-align: justify;\">E\u2019 stato ufficializzato il listino che per ora prevede tre versioni: benzina 1.4 TFSI parte da 27.900 euro, 2.200 euro in pi\u00f9 servono per la 1.4 TFSI con trasmissione automatica a doppia frizione S tronic (30.100 euro) e 26.200 euro \u00e8 il prezzo della 1.6 TDI, a gasolio. Per entrambi i motori sono disponibili gli \u00a0allestimenti base, Business (+2.500 euro), Sport (+1.600 euro) e Design (+1.600 euro).<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/colori-auto-piu-scelti-nel-2010-2010\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/12\/150a0_01-dupont-1291735386-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Colori auto pi\u00f9 scelti nel 2010<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ecco-8-trucchi-per-aumentare-il-valore-della-tua-auto-2016\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2016\/11\/car-repair-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ecco 8 trucchi per aumentare il valore della tua a...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/maserati-3500gt-convertibile-del-1959-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/10\/3500gt-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Maserati 3500GT Convertibile del 1959<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/pneumatici-in-arrivo-etichetta-salva-carburante-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/11\/Etichetta-pneumatici-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Pneumatici: in arrivo etichetta salva-carburante<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Dimensioni contenute, rifinita nei dettagli, vivace nei motori e linee robuste: \u00e8 la nuova Audi Q2 che arriver\u00e0 in Italia in autunno.E\u2019 la pi\u00f9 piccola tra le Suv della casa tedesca : lunga 419 cm, larga 179 cm e alta 151 cm compatta ma dalla linea robusta \u00a0per conservare il\u00a0carattere possente tipico dei Suv Audi. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[2108],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/12097"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=12097"}],"version-history":[{"count":2,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/12097\/revisions"}],"predecessor-version":[{"id":12104,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/12097\/revisions\/12104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media\/12098"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=12097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=12097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=12097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}