{"id":1260,"date":"2011-01-27T12:23:42","date_gmt":"2011-01-27T12:23:42","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=1260"},"modified":"2016-09-14T15:41:43","modified_gmt":"2016-09-14T14:41:43","slug":"presentazione-nuova-ferrari-formula-1-2011-f150","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/presentazione-nuova-ferrari-formula-1-2011-f150-2011","title":{"rendered":"Presentazione nuova Ferrari Formula 1 2011 F150"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/01\/321261_5013_big_Ferrari_F1501.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1261\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/01\/321261_5013_big_Ferrari_F1501.jpg\" alt=\"\" width=\"545\" height=\"370\" \/><\/a><\/p>\n<p>Giornata importante quella di domani per gli appassionati di Formula 1 e soprattutto per i tifosi Ferrari. Ancora qualche ora di pazienza e domani mattina alla 10.00 verr\u00e0 svelata la nuova Ferrari di Formula 1 per il campionato del mondo 2011. Della vettura non si conosce ancora nulla, al di fuori del nome: infatti&#8230;<\/p>\n<p><!--more--> la nuova arma del cavallino si chiamer\u00e0 F150, in onore dei 150 anni dell&#8217;unit\u00e0 d&#8217;Italia.<\/p>\n<p>&#8220;<em>La Ferrari<\/em> &#8211; ha dichiarato il presidente Luca di Montezemolo &#8211; <em>\u00e8 l&#8217;espressione dell&#8217;eccellenza, del talento e della creativit\u00e0 italiani. Tutti gli uomini e le donne che lavorano con impegno e passione a Maranello condividono l&#8217;orgoglio e la responsabilit\u00e0 di rappresentare il nostro Paese nel mondo ed \u00e8 con questo spirito che abbiamo voluto dedicare questa monoposto a un evento cos\u00ec importante per l&#8217;Italia intera<\/em>&#8220;.<\/p>\n<p>Probabilmente anche la livrea della Ferrari F150 rispecchier\u00e0 le parole del Presidente mettendo in evidenza un tricolore pi\u00f9 marcato sulla vettura.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-citroen-c1-per-scoprire-il-lato-bello-della-citta-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/02\/nuova-citroen-c1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova CITRO\u00cbN C1 per scoprire il lato bello della ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/citroen-presenta-al-vogue-fashions-night-out-la-ds3-cabrio-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/09\/citroen-ds3-cabrio-in-esclusiva-al-vogue-fashions-night-out-citroen-12123001-01-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Citro\u00ebn presenta al Vogue Fashion\u2019s Night Out la D...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/automotoretro-2013-fiat-espone-auto-dellavvocato-agnelli-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/02\/Fiat_agnelli-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Automotoretr\u00f2 2013: Fiat espone le auto dell&#8217...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/diffuso-il-listino-della-nuova-audi-q3-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/05\/Audi-Q3_13-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Diffuso il listino della nuova Audi Q3<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Giornata importante quella di domani per gli appassionati di Formula 1 e soprattutto per i tifosi Ferrari. Ancora qualche ora di pazienza e domani mattina alla 10.00 verr\u00e0 svelata la nuova Ferrari di Formula 1 per il campionato del mondo 2011. Della vettura non si conosce ancora nulla, al di fuori del nome: infatti&#8230; Potrebbe [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[318,58,152],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1260"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=1260"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1260\/revisions"}],"predecessor-version":[{"id":12889,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1260\/revisions\/12889"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=1260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=1260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=1260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}