{"id":1774,"date":"2011-03-11T11:46:41","date_gmt":"2011-03-11T11:46:41","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=1774"},"modified":"2016-09-14T14:57:05","modified_gmt":"2016-09-14T13:57:05","slug":"nuova-audi-rs3-sportback","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/nuova-audi-rs3-sportback-2011","title":{"rendered":"Nuova Audi RS3 Sportback"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1775\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/AudiRS3_00.jpg\" alt=\"\" width=\"547\" height=\"393\" \/><\/p>\n<p>Tra poche settimane Audi commercializzer\u00e0 la nuova A3 Sportback in versione RS. L&#8217;agguerrita compatta di Ingolstadt ha tutte le carte in regola per essere un piccolo bolide da pista o per essere anche una delle vetture pi\u00f9 performanti nel percorso casa ufficio.<\/p>\n<p><!--more--> Motore 2,5cc 5 cilindri in linea che eroga 340cv di potenza e 450 Nm di coppia massima, 0-100 km\/h in 4,6 secondi e velocit\u00e0 massima autolimitata a 250 km\/h. Davvero niente male come biglietto da visita. Inoltre la vettura \u00e8 dotata anche di cambio automatico sequenziale S tronic a\u00a07 rapporti e della trazione integrale Quattro.<\/p>\n<p>Inoltre come tutte le Audi in versione RS, anche la\u00a0RS3 Sportback\u00a0si riconosce dalle altre sorelle A3 meno pepate da alcuni accorgimenti estetici come\u00a0minigonne laterali pi\u00f9 vistose, nuovo paraurti anteriore pi\u00f9 aggressivo con prese d&#8217;aria maggiorate, nuovi terminali di scarico posteriori integrati in un nuovo diffusore, un nuovo spoiler pi\u00f9 grande sopra il lunotto posteriore e\u00a0 nuovi cerchi in lega sportivi da 19 pollici a cinque razze.<\/p>\n<p>La nuova Audi RS3 Sportback sar\u00e0 in vendita ad un prezzo base di 52.100 euro.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/mercedes-glk-design-carattere-e-rinnovata-sportivita-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/03\/mercedes-benz-glk-nuova-generazione-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mercedes GLK: design, carattere e rinnovata sporti...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/marussia-motors-b1-b2-2010\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/12\/Marussia_B1_B2__44-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Marussia Motors B1 & B2<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuove-informazioni-sulla-erede-della-ferrari-599-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/05\/ferrari599ok-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuove informazioni sulla erede della Ferrari 599<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/novita-hyundai-ecco-la-nuova-i20-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/08\/cq5dam.web_.650.600-11-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Novit\u00e0 Hyundai: ecco la nuova i20!<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Tra poche settimane Audi commercializzer\u00e0 la nuova A3 Sportback in versione RS. L&#8217;agguerrita compatta di Ingolstadt ha tutte le carte in regola per essere un piccolo bolide da pista o per essere anche una delle vetture pi\u00f9 performanti nel percorso casa ufficio. Potrebbe anche Interessarti Nuova Renault Clio e Renault ZOE: il nuovo stile R&#8230; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[14,466,467,468],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1774"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=1774"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1774\/revisions"}],"predecessor-version":[{"id":12598,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1774\/revisions\/12598"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=1774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=1774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=1774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}