{"id":1830,"date":"2011-03-17T14:48:01","date_gmt":"2011-03-17T14:48:01","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=1830"},"modified":"2016-09-14T15:41:22","modified_gmt":"2016-09-14T14:41:22","slug":"buon-compleanno-italia","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/buon-compleanno-italia-2011","title":{"rendered":"Buon compleanno Italia!"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1831\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/360stradale.jpg\" alt=\"\" width=\"572\" height=\"315\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/360stradale.jpg 635w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/360stradale-300x165.jpg 300w\" sizes=\"(max-width: 572px) 100vw, 572px\" \/><\/p>\n<p>Oggi 17 marzo 2011 in tutta Italia si festeggiano i 150 anni dell&#8217;unit\u00e0 della nostra nazione. Quale modo migliore per unirci ai festeggiamenti\u00a0se non quello di\u00a0ricordare alcune vetture simbolo di eccellenza italiana nel mondo che hanno esibito in bella mostra\u00a0il tricolore sulla propria livrea?<\/p>\n<p><!--more-->Prima fra tutte la Ferrari 360 Challenge Stradale del 2003,\u00a0coup\u00e8 nata dalla fortunata 360 Modena ma resa ancora pi\u00f9 sportiva, pi\u00f9 leggera e pi\u00f9 potente ed impreziosita dalla livrea caratterizzata dalla banda tricolore che correva per tutta la vettura.<\/p>\n<p><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/zonda-tricolore_100307147_l-500x312.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1832\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/zonda-tricolore_100307147_l-500x312.jpg\" alt=\"\" width=\"500\" height=\"312\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/zonda-tricolore_100307147_l-500x312.jpg 500w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/zonda-tricolore_100307147_l-500x312-300x187.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Altro simbolo nazionalistico la Pagani Zonda Tricolore del 2010, nata per celebrare i 50 anni di un altro simbolo vincente dell&#8217;Italia nel mondo, le frecce tricolori. Anche in questo caso la livrea della Zonda era particolarmente devota ai colori nazionali e in linea con quella degli aerei in uso alla pattuglia acrobatica.<\/p>\n<p><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/Gallardo-Tricolore1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1834\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/Gallardo-Tricolore1.jpg\" alt=\"\" width=\"586\" height=\"401\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/Gallardo-Tricolore1.jpg 586w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/Gallardo-Tricolore1-300x205.jpg 300w\" sizes=\"(max-width: 586px) 100vw, 586px\" \/><\/a><\/p>\n<p>Ultima in ordine di tempo la Lamborghini Gallardo Tricolore, presentata proprio in occasione del 150\u00b0 anniversario dell&#8217;unit\u00e0 d&#8217;Italia e caratterizzata dalla carrozzeria completamente bianca ed attraversata in lungo da una fascia tricolore sul lato del guidatore.<\/p>\n<p>Appuntamento tra altri 50 anni per festeggiare i 200 anni di unit\u00e0 d&#8217;Italia e nel frattempo buon compleanno Italia!<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/salone-dellauto-di-ginevra-2013-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/03\/Lamborghini-Veneno-2-1024x625-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Salone dell\u2019auto di Ginevra 2013<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/in-giro-per-leuropa-a-bordo-di-fiat-qubo-con-erasmus-dreamtrip-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/05\/qubo-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">In giro per l\u2019Europa a bordo di Fiat Qubo co...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/la-nissan-leaf-e-la-nuova-auto-dellanno-2011-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/04\/nissan-leaf-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">La Nissan Leaf \u00e8 la nuova Auto dell\u2019anno 201...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-porsche-918-rsr-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/01\/317978_4305_big_porsche-918-rsr-101-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova Porsche 918 RSR<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Oggi 17 marzo 2011 in tutta Italia si festeggiano i 150 anni dell&#8217;unit\u00e0 della nostra nazione. Quale modo migliore per unirci ai festeggiamenti\u00a0se non quello di\u00a0ricordare alcune vetture simbolo di eccellenza italiana nel mondo che hanno esibito in bella mostra\u00a0il tricolore sulla propria livrea? Potrebbe anche Interessarti La nuova Fiat 500 alla conquista della Cina? [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[492,465,493,491],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1830"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=1830"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1830\/revisions"}],"predecessor-version":[{"id":12882,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/1830\/revisions\/12882"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=1830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=1830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=1830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}