{"id":2131,"date":"2011-05-18T11:06:01","date_gmt":"2011-05-18T11:06:01","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=2131"},"modified":"2016-09-14T14:55:54","modified_gmt":"2016-09-14T13:55:54","slug":"nuovo-1-6-tdi-da-90cv-per-laudi-a1","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/nuovo-1-6-tdi-da-90cv-per-laudi-a1-2011","title":{"rendered":"Nuovo 1.6 tdi da 90cv per l&#8217;Audi A1"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-2132\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2011\/05\/257079_2036_big_240610_Audi_A1_10.jpg\" alt=\"\" width=\"525\" height=\"350\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/05\/257079_2036_big_240610_Audi_A1_10.jpg 750w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/05\/257079_2036_big_240610_Audi_A1_10-300x200.jpg 300w\" sizes=\"(max-width: 525px) 100vw, 525px\" \/><\/p>\n<p>La nuova Audi A1 completa la sua gamma motori con il lancio del 1.6tdi da 90cv: il motore\u00a01.6 diesel con la nuova\u00a0potenza si affianca ai gi\u00e0 esistenti\u00a01.6 tdi da 105cv e 1.4 tfsi benzina da 122 cv e 185 cv.<\/p>\n<p><!--more--><\/p>\n<p>Il nuovo 1.6 tdi da 90cv promette consumi ed emissioni ancora pi\u00f9 bassi del 105cv di pari cilindrata: infatti Audi dichiara alle voci consumo ed emissioni rispettivamente 3.8 litri per 100 km e 99g\/km.\u00a0\u00a0Molto importante in questo periodo il fatto che la nuova Audi A1 equipaggiata con il 1.6 tdi da 90cv possa essere guidata anche da un neo patentato in virt\u00f9 del rapporto peso\/potenza in linea con quelli stabiliti dalla legge attuale.<\/p>\n<p>La nuova A1 1.6 tdi da 90cv avr\u00e0 anche una completa dotazione di sicurezza di serie che comprende Esp, airbag frontali e laterali e protezione per la testa. La nuova versione da\u00a090cv del 1.6tdi\u00a0sar\u00e0 abbinata di serie al cambio manuale a\u00a0cinque rapporti: questa variante \u00e8 gi\u00e0 ordinabile a partire da 18.800 euro con l&#8217;allestimento Attraction e da 20.250 euro in Ambition.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/allard-j2x-2010\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/11\/allardmkii-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Allard J2X<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/sesso-in-autopiace-a-8-italiani-su-10-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/02\/sesso-in-auto-sondaggio-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Sesso in auto:piace a 8 italiani su 10<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/donne-al-volante-prudenza-costante-2017\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2017\/03\/donna-uomo-auto-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Donne al volante \u2026prudenza costante<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/sposarsi-a-bordo-della-chrysler-di-al-capone-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/02\/chrysler75-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Sposarsi a bordo della Chrysler di Al Capone<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>La nuova Audi A1 completa la sua gamma motori con il lancio del 1.6tdi da 90cv: il motore\u00a01.6 diesel con la nuova\u00a0potenza si affianca ai gi\u00e0 esistenti\u00a01.6 tdi da 105cv e 1.4 tfsi benzina da 122 cv e 185 cv. Potrebbe anche Interessarti Aprire e mettere in moto un\u2019auto con il tele&#8230; Automotive e social [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[545],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/2131"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=2131"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/2131\/revisions"}],"predecessor-version":[{"id":12565,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/2131\/revisions\/12565"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=2131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=2131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=2131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}