{"id":390,"date":"2010-06-05T14:28:02","date_gmt":"2010-06-05T14:28:02","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=390"},"modified":"2016-09-14T11:52:58","modified_gmt":"2016-09-14T10:52:58","slug":"touch-screen-land-rover-jaguar","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/touch-screen-land-rover-jaguar-2010","title":{"rendered":"Dual view touch screen Land Rover &#038; Jaguar"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2010\/06\/2010-range-rover-dash-small.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-392\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2010\/06\/2010-range-rover-dash-small.jpg\" alt=\"\" width=\"550\" height=\"250\" \/><\/a><\/p>\n<p>Le nuove ammiraglie di casa Jaguar e Land Rover, rispettivamente XJ e Range Rover Vogue, (entrambe controllate dalla casa indiana Tata) portano al debutto sul mercato un rivoluzionario sistema di comunicazione ed intrattenimento.<\/p>\n<p>Difatti il cliente di una di queste vetture potr\u00e0 ordinare come optional il \u201cDual View Touch Screen\u201d. Ma che cos\u2019\u00e8 e soprattutto come funziona il sistema?<\/p>\n<p><!--more--><\/p>\n<p>Lo schermo utilizzato da questo sistema \u00e8 lo stesso schermo del navigatore integrato nella plancia di tutti e due i modelli, per cui a vettura spenta non ci si pu\u00f2 rendere conto della sua presenza.<\/p>\n<p>La situazione cambia a vettura in moto, quando lo schermo del navigatore si accende e si avverte la presenza di questo accessorio, che ha una funzione alquanto unica e particolarmente appariscente.<\/p>\n<p>Il Dual View Touch Screen appare sempre come uno schermo a sfioramento perch\u00e8 praticamente \u00e8 sempre lo stesso del navigatore, ma ha la possibilit\u00e0 unica della doppia visualizzazione.<\/p>\n<p>Questo significa che guidatore e passeggero anteriore possono guardare lo stesso monitor nella plancia, ma con visualizzazioni differenti. Per esempio se il guidatore guarda il monitor con la relativa schermata relativa al navigatore, il passeggero pu\u00f2 guardare nello stesso momento lo stesso monitor ma con la schermata relativa alla tv. Oppure se il guidatore guarda nel monitor i dati relativi allo stato della vettura, il passeggero pu\u00f2 tranquillamente guardare un film in dvd.<\/p>\n<p>&#8220;Il Dual View Touch Screen&#8221;, come enunciato da Land Rover, &#8221;\u00a0ha una risoluzione di 1280 per 480 pixel e usa la tecnologia brevettata \u201cParallax Barrier\u201d per la visualizzazione di colonne di pixel alternativa da sinistra e da destra&#8221;.<\/p>\n<p>Non c\u2019\u00e8 che dire, davvero un accessorio innovativo, funzionale e scenografico per le due nuove classiche ammiraglie.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-peugeot-308-2011-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/02\/Peugeot308restyling2011_03-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova Peugeot 308 2011<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/toyota-arriva-il-sistema-di-fornitura-energetica-da-bus-a-idrogeno-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/09\/toyota_sitema-fornitura-energia-V2h-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Toyota: arriva il sistema di  fornitura energetica...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-evoque-test-drive-del-suv-compatto-di-casa-range-rover-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/04\/evoque-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova Evoque: test drive del Suv compatto di casa ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/fiat-500l-finalista-di-autobest-2013-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/10\/Fiat-500L-2012-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Fiat 500L: finalista di Autobest 2013<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Le nuove ammiraglie di casa Jaguar e Land Rover, rispettivamente XJ e Range Rover Vogue, (entrambe controllate dalla casa indiana Tata) portano al debutto sul mercato un rivoluzionario sistema di comunicazione ed intrattenimento. Difatti il cliente di una di queste vetture potr\u00e0 ordinare come optional il \u201cDual View Touch Screen\u201d. Ma che cos\u2019\u00e8 e soprattutto [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[127],"tags":[52,49,17,51,48,50],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/390"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/390\/revisions"}],"predecessor-version":[{"id":12287,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/390\/revisions\/12287"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}