{"id":4953,"date":"2012-03-29T15:51:46","date_gmt":"2012-03-29T14:51:46","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=4953"},"modified":"2016-09-14T11:52:16","modified_gmt":"2016-09-14T10:52:16","slug":"opel-rivoluziona-lilluminazione-nel-settore-automobilistico","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/opel-rivoluziona-lilluminazione-nel-settore-automobilistico-2012","title":{"rendered":"Opel rivoluziona l&#8217;illuminazione nel settore automobilistico"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" class=\"aligncenter  wp-image-4960\" style=\"border-image: initial; border-width: 1px; border-color: black; border-style: solid;\" title=\"opel-rivoluziona-lilluminazione-nel-settore-automobilistico\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2012\/03\/opel-rivoluziona-lilluminazione-nel-settore-automobilistico-275087.jpg\" alt=\"\" width=\"538\" height=\"366\" \/>La <strong>Opel<\/strong> ha sviluppato i rivoluzionari <strong>fari intelligenti a matrice<\/strong> che non abbagliano. Si tratta di un rivoluzionario sistema di illuminazione anteriore adattabile che render\u00e0 la guida notturna ancora pi\u00f9 sicura e rilassante. I prototipi di questi fari a LED sono in fase di test e la \u00a0nuova tecnologia opera insieme all\u2019Opel Eye, la telecamera anteriore che si trova tra il parabrezza e lo specchietto retrovisore. <!--more-->Quando i sensori dell\u2019Opel Eye rilevano fonti luminose provenienti dal traffico che precede o che procede in direzione opposta elaborano dei segnali che vengono inviati ai fari a matrice di LED. I fari abbaglianti sul lato del traffico proveniente dalla direzione opposta o che precede vengono automaticamente ridotti, mentre i fari sull\u2019altro lato restano accesi. A seconda della situazione, la riduzione dell\u2019intensit\u00e0 pu\u00f2 essere diversa, garantendo cos\u00ec l\u2019assenza di fastidi per gli altri utenti della strada, assicurando al contempo la visibilit\u00e0 di eventuali altri ostacoli non illuminati. L\u2019importanza di un\u2019ottima visibilit\u00e0 nel traffico stradale \u00e8 confermata dalle statistiche sugli incidenti: pur in presenza di circa il 33 per cento di traffico in meno sulle strade di notte, il numero di incidenti stradali mortali che avvengono dopo il tramonto o nell\u2019oscurit\u00e0 \u00e8 il doppio rispetto al giorno. Secondo alcuni studi, la maggiore luminosit\u00e0 dei fari allo xeno \u00e8 in grado di prevenire gli incidenti, e i fari a LED possono migliorare ulteriormente le statistiche relative agli incidenti.<\/p>\n<p><object width=\"560\" height=\"315\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/HsP6--jlJJU?version=3&amp;hl=it_IT\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed width=\"560\" height=\"315\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/HsP6--jlJJU?version=3&amp;hl=it_IT\" allowFullScreen=\"true\" allowscriptaccess=\"always\" allowfullscreen=\"true\" \/><\/object><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ecco-la-nuova-mercedes-classe-b-my2014-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/09\/cq5dam.web_.650.600-3-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ecco la nuova Mercedes Classe B my2014<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/maserati-ghibli-e-tesla-model-s-qual-e-la-migliore-2015\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2015\/03\/Maserati_Tesla-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Maserati Ghibli e Tesla Model S: qual \u00e8 la miglior...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-fiat-grande-punto-virgin-radio-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/06\/puntobbbbbbbbbbbbbbbbbbbbbbbbbbbbbbbbbbbb-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova Fiat Grande Punto Virgin Radio<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-ferrari-612-scaglietti-2010\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/12\/11111111111111111111111111111111.bmp') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova Ferrari 612 Scaglietti?<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>La Opel ha sviluppato i rivoluzionari fari intelligenti a matrice che non abbagliano. Si tratta di un rivoluzionario sistema di illuminazione anteriore adattabile che render\u00e0 la guida notturna ancora pi\u00f9 sicura e rilassante. I prototipi di questi fari a LED sono in fase di test e la \u00a0nuova tecnologia opera insieme all\u2019Opel Eye, la telecamera [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[127],"tags":[1026,658,1025],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/4953"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=4953"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/4953\/revisions"}],"predecessor-version":[{"id":12269,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/4953\/revisions\/12269"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=4953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=4953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=4953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}