{"id":5642,"date":"2012-05-21T14:44:46","date_gmt":"2012-05-21T13:44:46","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=5642"},"modified":"2016-09-14T15:39:46","modified_gmt":"2016-09-14T14:39:46","slug":"dealer-day-verona-a-volvo-il-primo-posto-assoluto-per-la-soddisfazione-dei-concessionari","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/dealer-day-verona-a-volvo-il-primo-posto-assoluto-per-la-soddisfazione-dei-concessionari-2012","title":{"rendered":"Dealer Day Verona: A Volvo il primo posto assoluto per la soddisfazione dei concessionari"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img class=\"aligncenter  wp-image-5646\" style=\"border: 1px solid black;\" title=\"volvo-premioDealerDayVerona\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2012\/05\/volvo-ottiene-il-primo-posto-assoluto-per-la-soddisfazione-dei-concessionari-in-occasione-dellautomotive-dealer-day-di-verona-43838-7-8.jpg\" alt=\"\" width=\"530\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/05\/volvo-ottiene-il-primo-posto-assoluto-per-la-soddisfazione-dei-concessionari-in-occasione-dellautomotive-dealer-day-di-verona-43838-7-8.jpg 1024w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/05\/volvo-ottiene-il-primo-posto-assoluto-per-la-soddisfazione-dei-concessionari-in-occasione-dellautomotive-dealer-day-di-verona-43838-7-8-300x200.jpg 300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Il <strong>premio<\/strong>\u00a0<strong>DealerSTAT, <\/strong>conferito durante il<strong> Dealer Day di Verona,<\/strong> \u00e8\u00a0stato assegnato sulla base dei\u00a0risultati emersi da 1.390 questionari, oss\u00eca il 45% dei concessionari italiani in rappresentanza di 34 Marchi\u00a0automobilistici.<!--more--><\/p>\n<p><strong>Volvo<\/strong> e <strong>Volvo Auto Italia<\/strong> si sono aggiudicate il primo posto ed il quarto per quanto riguarda la categoria di soddisfazione dei concessionari nel rapporto con la Casa automobilistica che\u00a0rappresentano.<\/p>\n<p>Le aree in cui\u00a0<strong>Volvo<\/strong> ha vinto sono:<\/p>\n<p><strong>&#8211; management vendite (incluse le vendite Flotte)<\/strong><br \/>\n<strong>&#8211; sistemi di incentivazione<\/strong><br \/>\n<strong>&#8211; programma usato<\/strong><br \/>\n<strong>&#8211; disponibilit\u00e0 al dialogo<\/strong><\/p>\n<p>Nelle altre categorie restanti, <strong>Volvo<\/strong> ha comunque ottenuto diversi secondi e terzi posti, come ad esempio in Management PostVendita (2\u00b0posto), Sistema Informativo della Casa (2\u00b0 posto), Training (2\u00b0 posto), Prodotto (3\u00b0posto) e Servizio Ricambi (3\u00b0 posto).<\/p>\n<p>Il premio<em> DealerSTAT<\/em> \u00e8 stato consegnato lo scorso\u00a0<em>Mercoled\u00ec 16 Maggio,\u00a0<\/em>seconda giornata\u00a0dell&#8217;<strong>Automotive Dealer Da<\/strong>y di Verona, ed \u00e8 stato consegnato a\u00a0<strong>Michele Crisci<\/strong>, <em>Amministratore Delegato di Volvo Auto Italia<\/em>.<\/p>\n<p>Di seguito il commento dell&#8217;amministratore delegato di Volvo Auto Italia, durante la consegna de premio:<br \/>\n<em>&#8220;Ogni premio \u00e8 importante e gi\u00e0 quello ricevuto lo scorso anno ci aveva particolarmente gratificato. Ma riuscire a\u00a0<\/em><em>replicare a distanza di un anno e in un momento di forte sofferenza del settore automobilistico ha un valore ancora\u00a0<\/em><em>pi\u00f9 grande. A decidere il vincitore sono, infatti, i Concessionari e ci\u00f2 significa che anche in condizioni di business\u00a0<\/em><em>tutt&#8217;altro che ideali siamo riusciti a fare le cose con seriet\u00e0. Questo voto, infatti, esprime non solo la soddisfazione\u00a0<\/em><em>dei concessionari verso la Casa, ma anche e soprattutto la qualit\u00e0 del lavoro svolto dall&#8217;azienda sul mercato.\u00a0<\/em><em>Esprime la capacit\u00e0 nel porsi al servizio efficacemente dei nostri partners, di risolvere loro i problemi e di guidarli e\u00a0<\/em><em>spingerli in modo proficuo nel prendere decisioni e direzioni di business. Lo scorso anno dissi che il premio era il\u00a0<\/em><em>frutto di una collaborazione fattiva ed efficace a tutti i livelli fra noi e la nostra Rete e che sarebbe stato un\u00a0<\/em><em>ulteriore stimolo per continuare a migliorarci per dare al nostro marchio altri successi; sono contento di poter dire\u00a0<\/em><em>che abbiamo mantenuto la parola&#8221;.<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/aston-martin-vanquish-volante-my2013-bellezza-a-cielo-aperto-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/06\/aston-martin-vanquish-volante-2013-vendiauto-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Aston Martin Vanquish Volante my2013: bellezza a c...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ford-go-further-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/06\/FORD-SYNC-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ford \u2013 Go Further<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/goodwod-festival-of-speed-2012-gioielli-a-quattro-ruote-di-ieri-e-di-oggi-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/07\/goodwood-2012-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Goodwod Festival of speed 2012: gioielli a quattro...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/i-calciatori-preferiscono-le-supercar-non-proprio-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/08\/Calciatori-e-auto-perch\u00e9-i-giocatori-di-calcio-non-dovrebbero-guidare-mario-balotelli-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">I calciatori preferiscono le supercar? Non proprio...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Il premio\u00a0DealerSTAT, conferito durante il Dealer Day di Verona, \u00e8\u00a0stato assegnato sulla base dei\u00a0risultati emersi da 1.390 questionari, oss\u00eca il 45% dei concessionari italiani in rappresentanza di 34 Marchi\u00a0automobilistici. Potrebbe anche Interessarti Confronto in grande stile: Audi A5 Sportback VS Bm&#8230; Nuova Bmw Serie 6 Coup\u00e8 Sar\u00e0 la DB10 la nuova Aston Martin di 007 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[1135,1134],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/5642"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=5642"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/5642\/revisions"}],"predecessor-version":[{"id":9831,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/5642\/revisions\/9831"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=5642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=5642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=5642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}