{"id":6144,"date":"2012-06-23T10:00:54","date_gmt":"2012-06-23T09:00:54","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=6144"},"modified":"2012-06-21T17:23:30","modified_gmt":"2012-06-21T16:23:30","slug":"diesel-pericolosi-per-la-salute-la-celpa-contesta-lo-studio-delloms","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/diesel-pericolosi-per-la-salute-la-celpa-contesta-lo-studio-delloms-2012","title":{"rendered":"Diesel pericolosi per la salute: la Celpa contesta lo studio dell\u2019OMS"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">I <strong>gas di scappamento dei motori diesel<\/strong> sono passati da essere classificati come \u201ccancerogeni probabili\u201d a \u201dcancerogeni certi\u201d per gli esseri umani. L\u2019esposizione a tali gas \u00e8 associata ad un \u00abrischio accresciuto di tumore al polmone\u00bb ed anche ad un maggior rischio di cancro alla vescica. <!--more-->Il verdetto arriva dal <strong>Centro internazionale di ricerca sul cancro (Circ\/Iarc)<\/strong> dell\u2019Organizzazione mondiale della Sanit\u00e0 (<strong>Oms<\/strong>). Lo studio riporta che i test sono stati compiuti su un campione di popolazione molto esposta agli scarichi diesel (minatori, lavoratori nei parcheggi) ed su questi soggetti che si \u00e8 rilevato un rischio elevato per il cancro. Ecco che il diesel diventa pericoloso oltre che per le tasche anche per la salute. A prendere per\u00f2 le difese dei diesel di ultima generazione \u00e8 arrivata la <strong>CLEPA<\/strong> (Comit\u00e9 de liaison europ\u00e9en des fabricants d&#8217;\u00e9quipements et de pi\u00e8ces automobiles); Jean-Marc Gales, neo eletto presidente della CLEPA ha dichiarato che lo studio non tiene conto dei progressi realizzati in materia di emissioni dai motori diesel negli ultimi dieci anni e per questo non pu\u00f2 essere accettato come riferimento definire delle iniziative. Considerando la grave situazione che vive oggi il mercato, non \u00e8 dunque opportuno secondo la Celpa \u00e8 inopportuno avanzare simili congetture pertanto invita l\u2019organismo promotore della ricerca ad approfondire gli studi in base alla situazione attuale.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/il-petrolio-finira-nel-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/07\/petrolio01-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Il petrolio finir\u00e0 nel\u2026.??<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/al-via-linternational-media-test-drive-dedicato-alla-f12berlinetta-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/07\/la-stampa-mondiale-mette-alla-prova-la-f12berlinetta-1200141-car-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Al via l\u2019International Media Test drive dedicato a...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/buon-compleanno-jaguar-e-type-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/02\/jaguar-e-type-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Buon compleanno Jaguar E Type!<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/porsche-918-spyder-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/01\/42eaf_porsche_918_spyder_concept_01-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Porsche 918 Spyder<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>I gas di scappamento dei motori diesel sono passati da essere classificati come \u201ccancerogeni probabili\u201d a \u201dcancerogeni certi\u201d per gli esseri umani. L\u2019esposizione a tali gas \u00e8 associata ad un \u00abrischio accresciuto di tumore al polmone\u00bb ed anche ad un maggior rischio di cancro alla vescica. Potrebbe anche Interessarti Grande successo per il noleggio di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[127],"tags":[1207,1208,1206],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/6144"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=6144"}],"version-history":[{"count":0,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/6144\/revisions"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=6144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=6144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=6144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}