{"id":7746,"date":"2012-11-26T16:06:36","date_gmt":"2012-11-26T15:06:36","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=7746"},"modified":"2016-09-14T15:38:07","modified_gmt":"2016-09-14T14:38:07","slug":"fiat-al-motor-show-di-bologna-con-la-panda-4x4","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/fiat-al-motor-show-di-bologna-con-la-panda-4x4-2012","title":{"rendered":"Fiat al Motor Show di Bologna con la Panda 4&#215;4"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img class=\"aligncenter  wp-image-7747\" style=\"border: 1px solid black;\" title=\"Fiat-Panda-4x4\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2012\/11\/Fiat-Panda-4x4.jpg\" alt=\"\" width=\"540\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/11\/Fiat-Panda-4x4.jpg 640w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/11\/Fiat-Panda-4x4-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Dal 5 al 9 dicembre apre le porte il <strong>Motor Show di Bologna<\/strong>,\u00a0l\u2019unica manifestazione automotive in cui poter\u00a0vedere e provare le novit\u00e0 del mercato. In occasione della 37esima edizione di\u00a0questo\u00a0grande evento il brand <strong>Fiat<\/strong> partecipa con una flotta di dieci <strong>Panda 4&#215;4<\/strong> messa a disposizione del pubblico per coinvolgenti test drive su un tracciato con ostacoli e diversi fondi stradali. <!--more-->Ospitata presso l&#8217;area esterna 47, all&#8217;interno del complesso fieristico di Bologna, la zona dedicata alla &#8216;Fiat Panda 4&#215;4&#8217; prevede,\u00a0 a ridosso del tracciato, un&#8217;area hospitality dove il pubblico potr\u00e0 ascoltare musica, bere un caff\u00e8\u00a0 e ammirare due esemplari della nuova vettura Fiat, l&#8217;unico modello a trazione integrale del segmento A.\u00a0Erede di un best seller che fece la sua prima apparizione 29 anni fa affermandosi come la pi\u00f9 piccola e intrigante &#8220;esploratrice&#8221; della categoria, oggi la nuova Panda a trazione integrale si conferma una vettura &#8220;tuttofare&#8221; pronta ad affrontare con la stessa disinvoltura mulattiere di montagna e &#8220;giungla&#8221; urbana.\u00a0Fiat Panda 4&#215;4 \u00e8 disponibile con due motorizzazioni, entrambe dotate di Start&amp;Stop: il nuovo 0.9 TwinAir Turbo da 85 CV e il diesel 1.3 Multijet II da 75 CV.<\/p>\n<p>&nbsp;<\/p>\n<p>Accompagnati da piloti professionisti, i visitatori dell&#8217;area &#8216;Panda 4&#215;4&#8217; potranno affrontare in totale sicurezza il tracciato che prevede una strada con strisce di mezzeria, attraversamento pedonale e un cantiere di &#8216;lavori in corso&#8217; dove spicca un camion trasporto mezzi movimento terra da superare,\u00a0 Il tutto reso ancora pi\u00f9 avvincente dal susseguirsi continuo di ponti, rampe e passaggi con differenti fondi (legno, pietra, ghiaia) e diverse altezze, lunghezze e pendenze che metteranno in evidenza le straordinarie doti off-road di Fiat Panda 4&#215;4.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;area allestita a Bologna \u00e8 stata realizzata dal brand Fiat in collaborazione con ACI-Vallelunga, la societ\u00e0 che amministra il polo multifunzionale dell&#8217;Autodromo di Vallelunga ubicato alle porte di Roma.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/le-auto-piu-belle-in-mostra-11-e-12-maggio-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/04\/Lancia-Stratos-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Le auto piu\u2019 belle in mostra 11 e 12 maggio<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/scoop-primo-teaser-della-nuova-aston-martin-lagonda-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/07\/lagonda-2014-news-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Scoop! Aston Martin fa rinascere la Lagonda: ecco ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/fuoriserie-2010-2-2010\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/04\/fuoriserie2010-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Fuoriserie 2010<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/test-drive-per-la-nuova-alfa-romeo-giulia-sotto-mentite-spoglie-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/12\/alfa-romeo-giulia-2015-foto-spia-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Test drive per la nuova Alfa Romeo Giulia\u2026so...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Dal 5 al 9 dicembre apre le porte il Motor Show di Bologna,\u00a0l\u2019unica manifestazione automotive in cui poter\u00a0vedere e provare le novit\u00e0 del mercato. In occasione della 37esima edizione di\u00a0questo\u00a0grande evento il brand Fiat partecipa con una flotta di dieci Panda 4&#215;4 messa a disposizione del pubblico per coinvolgenti test drive su un tracciato con [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[28,1374,1510],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/7746"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=7746"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/7746\/revisions"}],"predecessor-version":[{"id":12798,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/7746\/revisions\/12798"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=7746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=7746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=7746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}