{"id":8398,"date":"2013-03-21T16:28:35","date_gmt":"2013-03-21T15:28:35","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=8398"},"modified":"2016-09-14T11:40:17","modified_gmt":"2016-09-14T10:40:17","slug":"puegeot-insieme-alla-lilt-contro-il-tumore","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/puegeot-insieme-alla-lilt-contro-il-tumore-2013","title":{"rendered":"Puegeot insieme alla Lilt contro il tumore"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\"><img class=\"aligncenter  wp-image-8400\" style=\"border: 1px solid black;\" title=\"lilt-e-3008-hybrid4-insieme-contro-il-tumore\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2013\/03\/lilt-e-3008-hybrid4-insieme-contro-il-tumore.jpg\" alt=\"\" width=\"540\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/03\/lilt-e-3008-hybrid4-insieme-contro-il-tumore.jpg 640w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/03\/lilt-e-3008-hybrid4-insieme-contro-il-tumore-300x138.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>Peugeot<\/strong> e la Lega Italiana per la Lotta contro i Tumori insieme per raccogliere fondi a favore di una borsa di studio per un giovane medico che si\u00a0dedicher\u00e0 alla ricerca in materia di neoplasia polmonare.\u00a0La casa francese supporter\u00e0 l&#8217;iniziativa mettendo a disposizione una <strong>3008 HYbrid4<\/strong>, la\u00a0prima ibrida diesel al mondo.\u00a0<!--more-->La consegna della 3008 HYbrid4, che si aggiunge a quella precedente di una 508, s&#8217;inquadra nell&#8217;ambito della\u00a0collaborazione tra Peugeot e LILT, che \u00e8 anche promotrice della nona edizione della Settimana Nazionale della\u00a0Prevenzione Oncologica. L&#8217;obiettivo \u00e8 informare correttamente, sensibilizzare e rendere tutti\u00a0consapevoli che la prevenzione \u00e8 oggi l&#8217;arma vincente contro i tumori. La\u00a03008 HYbrid4 \u00e8 una delle vetture pi\u00f9 \u201cpulite\u201d attualmente presente sul mercato tanto da poter usufruire degli incentivi\u00a0governativi recentemente introdotti per le cosiddette auto a basse emissioni complessive. Tra l&#8217;altro, grazie al motore\u00a0elettrico montato posteriormente, pu\u00f2 circolare in citt\u00e0 in modalit\u00e0 ZEV (zero emission vehicle), quindi senza emissioni\u00a0allo scarico.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/cellulare-alla-guida-il-124-degli-automobilisti-utilizza-il-telefonino-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/12\/guida_telefono-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Cellulare alla guida: il 12,4% degli automobilisti...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/pininfarina-cambiano-la-berlina-sportiva-di-lusso-dal-cuore-ecosostenibile-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/02\/Pininfarina_Cambiano-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Pininfarina Cambiano: la Berlina sportiva di lusso...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/la-auto-piu-lussuose-dei-vip-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/01\/porsche_911_carrera-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">La auto pi\u00f9 lussuose dei VIP<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/chevrolet-volt-non-esistono-rischi-dincendio-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/01\/Chevrolet-Volt-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Chevrolet Volt: non esistono rischi d\u2019incendio<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Peugeot e la Lega Italiana per la Lotta contro i Tumori insieme per raccogliere fondi a favore di una borsa di studio per un giovane medico che si\u00a0dedicher\u00e0 alla ricerca in materia di neoplasia polmonare.\u00a0La casa francese supporter\u00e0 l&#8217;iniziativa mettendo a disposizione una 3008 HYbrid4, la\u00a0prima ibrida diesel al mondo.\u00a0 Potrebbe anche Interessarti Dual view [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/8398"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=8398"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/8398\/revisions"}],"predecessor-version":[{"id":12116,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/8398\/revisions\/12116"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=8398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=8398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=8398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}