{"id":883,"date":"2010-11-23T21:45:21","date_gmt":"2010-11-23T21:45:21","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=883"},"modified":"2016-09-14T14:59:39","modified_gmt":"2016-09-14T13:59:39","slug":"cadillac-escalade-platinum-edition","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/cadillac-escalade-platinum-edition-2010","title":{"rendered":"Cadillac Escalade Platinum Edition"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2010\/11\/2011-CADILLAC-ESCALADE-Pictures.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-884\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2010\/11\/2011-CADILLAC-ESCALADE-Pictures.jpg\" alt=\"\" width=\"530\" height=\"397\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/11\/2011-CADILLAC-ESCALADE-Pictures.jpg 585w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2010\/11\/2011-CADILLAC-ESCALADE-Pictures-300x224.jpg 300w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><\/a><\/p>\n<p>Con il model year &#8217;11 la pi\u00f9 mastodontica delle Suv (lunghezza 5,15, larghezza2,01 e\u00a0altezza 1,89)\u00a0la Cadillac Escalade potr\u00e0 essere ordinata nell&#8217;esclusiva versione Platinum.<\/p>\n<p><!--more--><\/p>\n<p>L&#8217;allestimento prevede degli accorgimenti estremamente lussuosi per gli interni tra cui sedili in pelle speciale lavorati e cuciti a mano da sapienti artigiani e pannelli del cruscotto con elegantissimi interni in frassino con finiture in alluminio, navigatore satellitare e sistema di intrattenimento dvd per i passeggeri posteriori, sedili a regolazione completamente elettrica e con memoria e per finire perfino un porta tazze riscaldabile!<\/p>\n<p>Anche gli esterni non sono da meno, caratterizzati da cerchi in lega tipicamente americani da 22&#8243; tutti cromati e soprattutto da pedane esterne estraibili automaticamente per facilitare la salita e la discesa dei passeggeri.<\/p>\n<p>Praticamente al cliente non resta che fare due cose per mettersi nel garage la nuova Cadillac Escalade Platinum Edition: scegliere il colore esterno della carrozzeria e fare un bonifico alla concessionaria Cadillac di 83.588 euro!<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/audi-city-londra-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/08\/audi-city-london-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Audi city Londra<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/la-nuova-baby-maserati-si-chiamera-levante-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/08\/maserati-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">La nuova baby Maserati si chiamer\u00e0 Levante?<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/nuova-infiniti-m35h-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/03\/infinity_m35h_2011_1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nuova Infiniti M35h<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/pirelli-e-supercar-connubio-perfetto-in-scena-al-salone-di-ginevra-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/03\/pirelli-salone-di-ginevra-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Pirelli e Supercar. Connubio perfetto in scena al ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Con il model year &#8217;11 la pi\u00f9 mastodontica delle Suv (lunghezza 5,15, larghezza2,01 e\u00a0altezza 1,89)\u00a0la Cadillac Escalade potr\u00e0 essere ordinata nell&#8217;esclusiva versione Platinum. Potrebbe anche Interessarti Hennessey Venom GT: una vettura che offre grandi s&#8230; Nuova Panda Van: dimensioni esterne compatte e van&#8230; Ecco la nuova Mercedes CLA Shooting Brake Grande successo commerciale per la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[195,196,2094],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/883"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=883"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/883\/revisions"}],"predecessor-version":[{"id":12668,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/883\/revisions\/12668"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}