{"id":9014,"date":"2013-07-10T12:16:20","date_gmt":"2013-07-10T11:16:20","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=9014"},"modified":"2016-09-14T11:43:58","modified_gmt":"2016-09-14T10:43:58","slug":"fine-produzione-per-la-bmw-m3-e92","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/fine-produzione-per-la-bmw-m3-e92-2013","title":{"rendered":"Fine produzione per la Bmw M3 E92"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2013\/07\/ultima-bmw-m3.jpg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-9015\" alt=\"ultima bmw-m3\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2013\/07\/ultima-bmw-m3.jpg\" width=\"640\" height=\"427\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/07\/ultima-bmw-m3.jpg 640w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/07\/ultima-bmw-m3-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Addio alla M3!!! Dopo ben 40.000 esemplari venduti dal 2007 ad oggi l&#8217;ultima generazione di M3, la E92, esce di scena e con lei va via anche la stessa denominazione che dal 1986 ha accompagnato tutte le varianti sportive della Serie 3 preparate dalla Motorsport.<\/p>\n<p><!--more-->Proprio cos\u00ec: in futuro non ci saranno pi\u00f9 M3 dal momento che Bmw ha deciso di rinominare Serie 4 le varianti coup\u00e8 e cabrio derivanti dalla Serie 3. In questo modo le prossime vetture firmate Motorsport saranno identificate conseguentemente col nome M4. E&#8217; un addio alla tradizione che lascia un po&#8217; l&#8217;amaro in bocca a chi in quella lettera associata a quel numero aveva identificato un modo di concepire una vettura super sportiva. Purtroppo, per motivi di marketing, non sar\u00e0 pi\u00f9 cos\u00ec. E negli anni a venire dovremmo abituarci all&#8217;idea del nome M4. L&#8217;ultima M3 uscita dalla catena di montaggio \u00e8 stata di colore sakhir orange. Ricordiamo che al momento la M3 E92 \u00e8 stata la prima e l&#8217;ultima ad adottare un motore ad otto cilindri 4.0 da 420 cv. Sulla nuova M4 invece si torner\u00e0 ad adottare un classico propulsore a sei cilindri, magari pi\u00f9 piccolo di cilindrata, ma coadiuvato da turbocompressori per assicurare sempre una notevole potenza.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ecco-la-nuova-mercedes-cla-shooting-brake-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/11\/cq5dam.web_.960.800-12-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ecco la nuova Mercedes CLA Shooting Brake<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/buon-compleanno-ayrton-2013\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/03\/ayrton-senna-image-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Buon compleanno Ayrton!<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/10934-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/09\/bewsGT_140024_cor-580x362-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Montezemolo lascia la Ferrari!<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/in-arrivo-la-nuova-vw-golf-cabriolet-2011\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2011\/06\/Volkswagen_Golf_Cabriolet_44-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">In arrivo la nuova VW Golf Cabriolet!<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Addio alla M3!!! Dopo ben 40.000 esemplari venduti dal 2007 ad oggi l&#8217;ultima generazione di M3, la E92, esce di scena e con lei va via anche la stessa denominazione che dal 1986 ha accompagnato tutte le varianti sportive della Serie 3 preparate dalla Motorsport. Potrebbe anche Interessarti Video teaser della nuova suv compatta di [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[1723],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/9014"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=9014"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/9014\/revisions"}],"predecessor-version":[{"id":12169,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/9014\/revisions\/12169"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=9014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=9014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=9014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}