{"id":9220,"date":"2013-09-21T15:48:26","date_gmt":"2013-09-21T14:48:26","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=9220"},"modified":"2016-09-14T11:46:02","modified_gmt":"2016-09-14T10:46:02","slug":"salone-di-francoforte-2013","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/salone-di-francoforte-2013-2013","title":{"rendered":"Salone di Francoforte 2013"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><img class=\"wp-image-9221 aligncenter\" style=\"border: 1px solid black;\" alt=\"salone_di_francoforte_2013_vendiauto\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2013\/09\/salone_di_francoforte_2013_vendiauto.jpg\" width=\"540\" srcset=\"https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/09\/salone_di_francoforte_2013_vendiauto.jpg 620w, https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2013\/09\/salone_di_francoforte_2013_vendiauto-300x169.jpg 300w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/p>\n<p>Domani, domenica 22 Settembre, caler\u00e0 il sipario sulla 65esima edizione del Salone di Francoforte: un appuntamento, quello tedesco, che ha avuto il merito di portare entusiasmo e nuove idee al tracollante mondo dell\u2019auto che mai come in questo momento storico ha bisogno di vitalit\u00e0 e voglia di ripartire. Probabilmente l\u2019edizione di quest\u2019anno verr\u00e0 ricordata proprio per questo: sia il milione di spettatori che i 12.000 giornalisti accreditati hanno esaltato i nuovi modelli del futuro presentati con tanto ardore dai relativi costruttori.<\/p>\n<p><!--more-->Il segnale forte che vuole lasciare questo Salone \u00e8 uno solo: la crisi \u00e8 quasi terminata ed il rilancio del mercato automobilistico \u00e8 quasi pronto a decollare nuovamente. Il pi\u00f9 citato \u201cquasi\u201d sembra quindi destinato ad essere un avverbio del recente passato che non apparterr\u00e0 pi\u00f9 al prossimo futuro: se il precedente Salone di Ginevra di Marzo aveva fatto gi\u00e0 da apripista con la sua sfolgorante carica di novit\u00e0 e supercar portate al debutto, ora il Salone di Francoforte suggella questo trend. Andiamo ora a vedere nel dettaglio le novit\u00e0 pi\u00f9 significative del salone tedesco partendo da quella che pu\u00f2 essere definita la regina: la <b>Ferrari 458 Speciale<\/b>. L\u2019ultima nata della casa di Maranello si presenta come una versione estrema della 458 Italia: propulsore V8 portato a 605 cv, appendici aerodinamiche mobili, innovativo controllo elettronico dell\u2019angolo di assetto e peso limato a 1.290 kg fanno diventare la Speciale la vettura ad otto cilindri aspirata pi\u00f9 potente e veloce della storia Ferrari potendo contare su prestazioni da brivido (0-100 km\/h in 3 secondi e 0-200 km\/h in 9,1 secondi). Non resta a guardare la Porsche che dopo Ginevra porta anche a Francoforte la innovativa <b>918 Spyder<\/b> che in un corpo da favola nasconde la sua natura ibrida in grado di combinare un motore termico V8 da 608 cv con due elettrici da 130 cv all\u2019asse anteriore e 156 cv all\u2019asse posteriore arrivando cos\u00ec ad una potenza combinata di ben 887 cv.<\/p>\n<p>Non potevano certamente deludere le tre sorelle Bmw, Audi e Mercedes. Bmw presenta in anteprima assoluta e pronta alla commercializzazione la <b>i3<\/b>, prima utilitaria elettrica a quattro posti del marchio dell\u2019elica che dispone di un motore da 170 cv alimentato da batterie agli ioni di litio che consentono un\u2019autonomia di 200 km. Curiosit\u00e0: al momento dell\u2019acquisto si pu\u00f2 ordinare come optional anche un piccolo motore termico bicilindrico da 34 cv che assicura altri 100 km di autonomia. Se Bmw punta sulle compatte, Audi e Mercedes si sfidano sul segmento delle ammiraglie presentando rispettivamente le nuove A8 e Classe S: potremmo quasi dire evoluzione contro rivoluzione. La <b>A8<\/b>, infatti, porta al design estremo il family feeling di Audi essendo caratterizzata da un\u2019enorme calandra, nuovi gruppi ottici completamente a led ed una carrozzeria che richiama nei tratti essenziali la precedente versione. La <b>Classe S<\/b> invece abbandona il design della precedente generazione abbracciando quello inaugurato con le nuove Classi A e B e fatto da linee curvilinee estremamente pulite: ora il design \u00e8 certamente meno massiccio della vecchia versione (i vistosi passaruota non ci sono pi\u00f9) e sicuramente pi\u00f9 elegante e filante (anche grazie alla fiancata \u201cdivisa\u201d in due da una linea che parte dal muso e che va ad \u201cappoggiarsi\u201d sul passaruota posteriore). Tra le ammiraglie va fatta menzione della nuova <b>Cadillac CTS<\/b> che si rinnova nelle linee ma senza abbandonare la spigolosit\u00e0 di design che da sempre l\u2019ha caratterizzata.<\/p>\n<p>Ammiraglie a parte, molto successo hanno avuto i Suv: Jaguar ha stupito tutti presentando il prototipo <b>C-X17<\/b>, il primo crossover dalla storia del marchio del giaguaro, Bmw ha lanciato la terza generazione di <b>X5<\/b> dalle classiche forme ma stavolta incattivite, soprattutto nel frontale, grazie al nuovo family feeling. Mercedes ha presentato il Suv compatto <b>GLA<\/b>, dove design e tecnica derivano direttamente dalla recente Classe A. Tra i marchi non premium molto successo hanno riscontrato la Dacia <b>Duster<\/b> rinnovata nel frontale, la ristilizzata Skoda <b>Yeti<\/b> sempre molto apprezzata dai giovani e la Peugeot <b>3008<\/b>, crossover che a quattro anni dal debutto ha ricevuto in dote il design dell\u2019ultimo family feeling del marchio del leone. Tra le berline medie ha suscitato molto interesse la neonata Mazda <b>3<\/b> ispirata al Koko design e caratterizzata da un forte dinamismo nelle linee. Tra le piccole invece a farsi notare sono state le vetture dagli occhi a mandorla: la nuovissima Hyundai i10, la rinnovata Nissan Micra e la versione aggiornata della Suzuki Swift.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/land-rover-chalet-2012-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/02\/chalet-landrover-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Land Rover Chalet 2012<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/dacia-duster-sempre-piu-ambito-il-suv-low-cost-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/11\/Dacia-Duster-Spot1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Dacia Duster: sempre pi\u00f9 ambito il Suv low cost!<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/i-consigli-di-bridgestone-per-una-guida-sicura-nella-stagione-invernale-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/12\/bridgestone-offre-consigli-per-una-guida-sicura-nella-stagione-invernale-2012-bs-weather-control-2-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">I consigli di Bridgestone per una guida sicura nel...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/la-nuova-bentley-continental-gtc-v8-debutta-in-nord-america-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/04\/la-nuova-bentley-continental-gtc-v8-debutta-in-nord-america-1-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">La Nuova Bentley Continental GTC V8 debutta in Nor...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Domani, domenica 22 Settembre, caler\u00e0 il sipario sulla 65esima edizione del Salone di Francoforte: un appuntamento, quello tedesco, che ha avuto il merito di portare entusiasmo e nuove idee al tracollante mondo dell\u2019auto che mai come in questo momento storico ha bisogno di vitalit\u00e0 e voglia di ripartire. Probabilmente l\u2019edizione di quest\u2019anno verr\u00e0 ricordata proprio [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[1747],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/9220"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=9220"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/9220\/revisions"}],"predecessor-version":[{"id":12192,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/9220\/revisions\/12192"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=9220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=9220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=9220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}