{"id":973,"date":"2010-12-17T17:11:28","date_gmt":"2010-12-17T17:11:28","guid":{"rendered":"http:\/\/www.vendiauto.com\/blog\/?p=973"},"modified":"2016-09-14T15:41:54","modified_gmt":"2016-09-14T14:41:54","slug":"mini-countryman-all4-racing","status":"publish","type":"post","link":"https:\/\/vendiauto.com\/blog\/mini-countryman-all4-racing-2010","title":{"rendered":"Mini Countryman All4 racing"},"content":{"rendered":"\n<!-- Quick Adsense WordPress Plugin: http:\/\/quickadsense.com\/ -->\n<div style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--leonative-->\r\n<!-- 5x1 -->\r\n<div id='div-gpt-ad-5x1-0' class='div-gpt-ad div-gpt-ad-inread'>\r\n<script type='text\/javascript'>\r\ngoogletag.cmd.push(function() { googletag.display('div-gpt-ad-5x1-0'); });\r\n<\/script>\r\n<\/div>\n<\/div>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2010\/12\/dakar_1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-974\" style=\"border: 1px solid black;\" src=\"http:\/\/www.vendiauto.com\/blog\/wp-content\/uploads\/2010\/12\/dakar_1.jpg\" alt=\"\" width=\"536\" height=\"430\" \/><\/a><\/p>\n<p>Appena nata in casa Mini, la Countryman ha registrato ampi consensi da parte del pubblico. Questo\u00a0consenso si \u00e8 presto trasformato in un ottimo avvio nelle vendite che lascia presupporre certamente\u00a0anche un ottimo risultato commerciale per casa madre.<\/p>\n<p><!--more--><\/p>\n<p>E ottimi risultati la Mini li vuole ottenere anche con la Countryman in vestito da corsa! Infatti \u00e8 di\u00a0poco tempo fa la notizia che\u00a0Mini sarebbe tornata ai rally\u00a0proprio partendo dalla Countryman.<\/p>\n<p>E cos\u00ec in attesa di partecipare al campionato mondiale rally 2011, assieme all&#8217;esperienza della squadra corse ufficiale Prodrive, la Mini svolger\u00e0 i primi test corsaioli con una Countryman in assetto da corsa sulle strade francesi di Le Creusot in vista della partecipazione gi\u00e0\u00a0confermata alla prossima edizione della Parigi-Dakar, che\u00a0partir\u00e0 il prossimo 1 gennaio 2011 e si snoder\u00e0 tra le strade di Argentina e Cile.<\/p>\n<p>Il pilota francese, Guerlain Chicherit,\u00a0che guider\u00e0 la Mini Countryman\u00a0nella prossima Parigi-Dakar, gi\u00e0 dopo soli 300 km\u00a0di test si \u00e8 rivelato entusiasto del comportamento stradale della nuova Countryman definendo &#8220;ottimi la manovrabilit\u00e0, il bilanciamento e anche la visibilit\u00e0&#8221;. Parole di elogio sono state espresse anche per il motore, un sei cilindri 3.000cc biturbo accreditato di una potenza di 315cv e con una coppia di 700Nm.<\/p>\n<p>La Countryman \u00e8 nata sicuramente sottouna buona stella dal punto di vista commerciale e ora\u00a0baster\u00e0 qualche giorno di pazienza\u00a0per sapere\u00a0se briller\u00e0 anche dal punto di vista sportivo.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div><!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.88'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h2>Potrebbe anche Interessarti <\/h2><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ecco-la-nuova-ferrari-california-t-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/02\/ferrari_california_t_2014_4dietro-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ecco la nuova Ferrari California T<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/fotografata-su-strada-la-nuova-skoda-superb-my2015-2014\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2014\/12\/1901791_737874909638306_4127305808562291902_n-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Fotografata su strada la nuova Skoda Superb my2015...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/dopo-la-v40-volvo-rilancia-con-la-xc40-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/09\/Volvo-XC40-immagini-senza-veli-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Dopo la V40 Volvo rilancia con la XC40?<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/vendiauto.com\/blog\/ever-il-sistema-che-ricarica-le-auto-elettriche-mentre-viaggiano-2012\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/vendiauto.com\/blog\/wp-content\/uploads\/2012\/07\/ever-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ever: il sistema che ricarica  le auto elettriche ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Appena nata in casa Mini, la Countryman ha registrato ampi consensi da parte del pubblico. Questo\u00a0consenso si \u00e8 presto trasformato in un ottimo avvio nelle vendite che lascia presupporre certamente\u00a0anche un ottimo risultato commerciale per casa madre. Potrebbe anche Interessarti Bmw serie 6 coup\u00e8 Fiat 500 Cult nel nuovo spot con Paolo Sorrentino Suv o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2110],"tags":[74,46,45,222],"_links":{"self":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/973"}],"collection":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/comments?post=973"}],"version-history":[{"count":1,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/973\/revisions"}],"predecessor-version":[{"id":12894,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/posts\/973\/revisions\/12894"}],"wp:attachment":[{"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/media?parent=973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/categories?post=973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vendiauto.com\/blog\/wp-json\/wp\/v2\/tags?post=973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}